{"id":38710,"date":"2022-10-06T15:00:57","date_gmt":"2022-10-06T11:30:57","guid":{"rendered":"https:\/\/www.paziresh24.com\/blog\/?p=38710"},"modified":"2022-10-06T11:02:53","modified_gmt":"2022-10-06T07:32:53","slug":"%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5","status":"publish","type":"post","link":"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/","title":{"rendered":"\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u06cc\u0627 \u0628\u0631\u0635"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_81 counter-hierarchy ez-toc-counter-rtl ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA\" >\u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0686\u06cc\u0633\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B1%D9%88%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\" >\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%AE%D8%A7%DA%A9_%D8%B1%D8%B3_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\" >\u062e\u0627\u06a9 \u0631\u0633 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D9%84%DB%8C%D9%88%D8%A7%D9%86_%D9%85%D8%B3%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\" >\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u06cc\u0648\u0627\u0646 \u0645\u0633\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D9%BE%D8%A7%D9%BE%D8%A7%DB%8C%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\" >\u067e\u0627\u067e\u0627\u06cc\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%A8%D8%B1%DA%AF_%D8%B1%DB%8C%D8%AD%D8%A7%D9%86_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\" >\u0628\u0631\u06af \u0631\u06cc\u062d\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%DA%AF%D8%B1%D8%AF%D9%88_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\" >\u06af\u0631\u062f\u0648 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D9%85%D9%88%D8%A7%D8%AF_%D8%BA%D8%B0%D8%A7%DB%8C%DB%8C_%DA%A9%D9%87_%D8%AF%D8%B1_%D8%AA%D8%B1%DA%A9%DB%8C%D8%A8%D8%B4%D8%A7%D9%86_%D8%B2%DB%8C%D9%86%DA%A9_%D8%AF%D8%A7%D8%B1%D9%86%D8%AF\" >\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0628\u0634\u0627\u0646 \u0632\u06cc\u0646\u06a9 \u062f\u0627\u0631\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D9%88%DB%8C%D8%AA%D8%A7%D9%85%DB%8C%D9%86_%D8%B3%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\" >\u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0633\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B9%D8%B3%D9%84_%D9%88_%D8%A8%D8%B1%DA%AF_%DA%86%D8%B1%DB%8C%D8%B4_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\" >\u0639\u0633\u0644 \u0648 \u0628\u0631\u06af \u0686\u0631\u06cc\u0634 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B2%D8%B1%D8%AF%DA%86%D9%88%D8%A8%D9%87_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\" >\u0632\u0631\u062f\u0686\u0648\u0628\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%A8%D8%B1%DA%AF_%D8%AF%D8%B1%D8%AE%D8%AA_%D8%A7%D9%86%D8%A7%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\" >\u0628\u0631\u06af \u062f\u0631\u062e\u062a \u0627\u0646\u0627\u0631 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B2%D9%86%D8%AC%D8%A8%DB%8C%D9%84_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\" >\u0632\u0646\u062c\u0628\u06cc\u0644 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#_%D8%A2%D9%84%D9%88%D8%A6%D9%87%E2%80%8C%D9%88%D8%B1%D8%A7\" >\u00a0\u0622\u0644\u0648\u0626\u0647\u200c\u0648\u0631\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B3%D8%B1%DA%A9%D9%87_%D8%B3%DB%8C%D8%A8\" >\u0633\u0631\u06a9\u0647 \u0633\u06cc\u0628<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B3%D8%AE%D9%86_%D9%86%D9%87%D8%A7%DB%8C%DB%8C\" >\u0633\u062e\u0646 \u0646\u0647\u0627\u06cc\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\" >\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644 \u062f\u0631 \u0645\u0648\u0631\u062f \u0631\u0627\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%AE%D9%88%D8%B1%D8%AF%D9%86_%DA%86%D9%87_%D8%BA%D8%B0%D8%A7%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C_%D8%B6%D8%B1%D8%B1_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\" >\u062e\u0648\u0631\u062f\u0646 \u0686\u0647 \u063a\u0630\u0627\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0636\u0631\u0631 \u062f\u0627\u0631\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%AC%D9%87_%D8%BA%D8%B0%D8%A7%D9%87%D8%A7%DB%8C%DB%8C_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D9%85%D9%84%D8%A7%D9%86%DB%8C%D9%86_%D8%B1%D8%A7_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF%D8%9F\" >\u062c\u0647 \u063a\u0630\u0627\u0647\u0627\u06cc\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u0627\u0646\u06cc\u0646 \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.paziresh24.com\/blog\/38710\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d8%ae%d8%a7%d9%86%da%af%db%8c-%d9%be%db%8c%d8%b3%db%8c-%db%8c%d8%a7-%d8%a8%d8%b1%d8%b5\/#%D8%A2%DB%8C%D8%A7_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C_%D8%AF%D8%B1_%D8%B7%D8%A8_%D8%B3%D9%86%D8%AA%DB%8C_%D9%82%D8%A7%D8%A8%D9%84_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0622\u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u062f\u0631 \u0637\u0628 \u0633\u0646\u062a\u06cc \u0642\u0627\u0628\u0644 \u062f\u0631\u0645\u0627\u0646 \u0627\u0633\u062a\u061f<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<p>\u0628\u06cc\u0645\u0627\u0631\u06cc <a href=\"https:\/\/www.paziresh24.com\/blog\/9200\/symptoms-treatment-and-prevention\/\" data-internallinksmanager029f6b8e52c=\"1709\" title=\"\u067e\u06cc\u0633\u06cc \u06cc\u0627 \u0628\u0631\u0635 \u0686\u06cc\u0633\u062a\u061f \u0639\u0644\u0627\u0626\u0645\u060c \u0639\u0644\u0644 \u0627\u0628\u062a\u0644\u0627\u060c \u0648 \u0627\u0646\u0648\u0627\u0639 \u0631\u0627\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0622\u0646\">\u067e\u06cc\u0633\u06cc<\/a> \u06cc\u0627 \u0628\u0631\u0635 (\u0628\u0647 \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc: Vitiligo) \u0646\u0648\u0639\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631 \u0627\u062b\u0631 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0622\u0646 \u062f\u0631 \u0638\u0627\u0647\u0631 \u067e\u0648\u0633\u062a \u0628\u06cc\u0645\u0627\u0631 \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f\u06cc \u0646\u0645\u0627\u06cc\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u0645\u0627 \u062f\u0644\u06cc\u0644 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0627 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0627\u062b\u0631 \u0622\u0646 \u0631\u0627 \u06a9\u0645\u200c\u0631\u0646\u06af\u200c\u062a\u0631 \u06a9\u0631\u062f\u061f \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0637\u0644\u0628 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627 \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u067e\u0627\u0633\u062e \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644\u200c\u0647\u0627\u060c \u0686\u0646\u062f \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u06cc\u0627 \u0628\u0631\u0635 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA\"><\/span>\u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0686\u06cc\u0633\u062a<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0686\u06cc\u0633\u062a\u060c \u0686\u0647 \u0639\u0644\u0627\u0626\u0645\u06cc \u062f\u0627\u0631\u062f \u0648 \u0634\u0631\u0648\u0639 \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0686\u06af\u0648\u0646\u0647 \u0627\u0633\u062a. \u067e\u06cc\u0633\u06cc \u06cc\u0627 \u0628\u0631\u0635 \u06cc\u06a9 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0627\u062f\u0627\u0645\u200c\u0627\u0644\u0639\u0645\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0646\u0634\u0627\u0646\u0647 \u0627\u0635\u0644\u06cc \u0622\u0646 \u0638\u0627\u0647\u0631 \u0634\u062f\u0646 \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0631\u0648\u06cc \u067e\u0648\u0633\u062a \u0627\u0633\u062a.<\/p>\n<p>\u0639\u0644\u062a \u0627\u06cc\u0646 \u0633\u0641\u06cc\u062f\u06cc \u06a9\u0645\u0628\u0648\u062f \u0631\u0646\u06af\u062f\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0644\u0627\u0646\u06cc\u0646 \u062f\u0631 \u0622\u0646 \u0646\u0648\u0627\u062d\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0647\u0631 \u0642\u0633\u0645\u062a\u06cc \u0627\u0632 \u067e\u0648\u0633\u062a \u0631\u0627 \u062f\u0631\u06af\u06cc\u0631 \u06a9\u0646\u062f\u060c \u0627\u0645\u0627 \u0645\u0639\u0645\u0648\u0644\u0627 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0635\u0648\u0631\u062a\u060c \u062f\u0633\u062a\u200c\u0647\u0627 \u0648 <a href=\"https:\/\/www.paziresh24.com\/blog\/16201\/%da%86%db%8c%d9%86-%d9%88-%da%86%d8%b1%d9%88%da%a9-%d9%be%d9%88%d8%b3%d8%aa\/\" data-internallinksmanager029f6b8e52c=\"1721\" title=\"\u0639\u0644\u0644 \u0686\u06cc\u0646 \u0648 \u0686\u0631\u0648\u06a9 \u0648 \u0631\u0627\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0686\u0631\u0648\u06a9 \u0634\u062f\u0646 \u067e\u0648\u0633\u062a \u0635\u0648\u0631\u062a\">\u0686\u06cc\u0646 \u0648 \u0686\u0631\u0648\u06a9<\/a>\u200c\u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<p>\u0646\u0648\u0627\u062d\u06cc \u0631\u0646\u06af\u200c\u067e\u0631\u06cc\u062f\u0647 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0641\u062a\u0627\u0628 \u0622\u0633\u06cc\u0628\u200c\u067e\u0630\u06cc\u0631\u062a\u0631 \u0647\u0633\u062a\u0646\u062f\u060c \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0645\u0631\u0627\u0642\u0628\u062a \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0631\u0645\u200c\u0647\u0627\u06cc \u0636\u062f\u0622\u0641\u062a\u0627\u0628 \u0645\u0646\u0627\u0633\u0628 \u0647\u0646\u06af\u0627\u0645 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0622\u0641\u062a\u0627\u0628 \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0627\u0647\u0645\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B1%D9%88%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\"><\/span>\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f. \u0628\u0627 \u0627\u06cc\u0646\u200c\u062d\u0627\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648\u060c \u0637\u0628 \u0633\u0646\u062a\u06cc \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u0631\u0627 \u06a9\u0645\u200c\u0631\u0646\u06af\u200c\u062a\u0631 \u06a9\u0631\u062f.<\/p>\n<p>\u062f\u06a9\u062a\u0631 \u0645\u062d\u0645\u062f\u062d\u0633\u06cc\u0646 \u062e\u06cc\u0631\u0627\u0646\u062f\u06cc\u0634 \u0645\u062a\u062e\u0635\u0635\u00a0\u0637\u0628 \u0633\u0646\u062a\u06cc\u060c \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0631\u0635 \u0631\u0627 \u0628\u0644\u063a \u0646\u0627\u067e\u062e\u062a\u0647 \u062a\u0639\u0631\u06cc\u0641 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631\u0645\u0627\u0646 \u0628\u0631\u0635 \u062f\u06a9\u062a\u0631 \u062e\u06cc\u0631\u0627\u0646\u062f\u06cc\u0634 \u0634\u0627\u0645\u0644 \u0645\u0635\u0631\u0641 \u0633\u0631\u06a9\u0647 \u0627\u0646\u06af\u0628\u06cc\u0646 \u0627\u0633\u062a \u0627\u0645\u0627 \u0645\u0648\u0627\u062f \u062e\u0648\u0631\u0627\u06a9\u06cc \u062f\u06cc\u06af\u0631\u06cc \u0646\u06cc\u0632 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u0631\u0627\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/p>\n<p>\u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0642\u0628\u0644 \u0627\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0647\u0631 \u0631\u0648\u0634 \u0628\u0647 \u06a9\u0645\u06a9 \u0633\u0627\u0645\u0627\u0646\u0647 <a href=\"https:\/\/www.paziresh24.com\/\" data-internallinksmanager029f6b8e52c=\"13\" title=\"\u067e\u0630\u06cc\u0631\u0634 \u06f2\u06f4\">\u067e\u0630\u06cc\u0631\u0634\u06f2\u06f4<\/a> \u0628\u0627 <a href=\"https:\/\/www.paziresh24.com\/s\/ir\/dermatology\/?turn_type=consult\" data-internallinksmanager029f6b8e52c=\"48\" title=\"\u0645\u0634\u0627\u0648\u0631\u0647 \u0622\u0646\u0644\u0627\u06cc\u0646 \u067e\u0648\u0633\u062a \u0648 \u0645\u0648\">\u062f\u06a9\u062a\u0631 \u067e\u0648\u0633\u062a \u0622\u0646\u0644\u0627\u06cc\u0646<\/a> \u0645\u0634\u0648\u0631\u062a \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0646\u0638\u0631 \u06cc\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0631\u0627 \u0646\u06cc\u0632 \u062f\u0631 \u0645\u0648\u0631\u062f \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0648 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631\u06cc \u0622\u0646\u200c\u0647\u0627 \u0628\u062f\u0627\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AE%D8%A7%DA%A9_%D8%B1%D8%B3_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\"><\/span>\u062e\u0627\u06a9 \u0631\u0633 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062e\u0627\u06a9 \u0631\u0633 \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0644\u06a9 \u067e\u06cc\u0633\u06cc \u0627\u0633\u062a. \u062e\u0627\u06a9 \u0631\u0633 \u0633\u0631\u0634\u0627\u0631 \u0627\u0632 \u0645\u0633 \u0627\u0633\u062a \u0648 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u067e\u0648\u0633\u062a \u062f\u0627\u0631\u062f. \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u0646 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9\u00a0\u0642\u0627\u0634\u0642 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc \u0622\u0628 \u0632\u0646\u062c\u0628\u06cc\u0644 \u0631\u0627 \u0628\u0647 \u06f2 \u0642\u0627\u0634\u0642 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc \u062e\u0627\u06a9 \u0631\u0633 \u0642\u0631\u0645\u0632 \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u0645\u062e\u0644\u0648\u0637 \u0631\u0627 \u0647\u0631 \u0631\u0648\u0632 \u0631\u0648\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0628\u06af\u0630\u0627\u0631\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0645\u0627\u0633\u0627\u0698 \u062f\u0647\u06cc\u062f. \u0622\u0628 \u0632\u0646\u062c\u0628\u06cc\u0644 \u062c\u0631\u06cc\u0627\u0646 \u062e\u0648\u0646 \u0631\u0627 \u062f\u0631 \u0645\u062d\u0644 \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f \u0648 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648 \u06cc\u06a9\u06cc \u0627\u0632 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D9%84%DB%8C%D9%88%D8%A7%D9%86_%D9%85%D8%B3%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\"><\/span>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u06cc\u0648\u0627\u0646 \u0645\u0633\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u06a9\u0627\u0641\u06cc \u0628\u0647\u200c\u0634\u06a9\u0644 \u06a9\u0644\u06cc \u0628\u0647 \u0633\u0644\u0627\u0645\u062a \u0628\u062f\u0646 \u0648 \u0637\u0631\u0627\u0648\u062a \u067e\u0648\u0633\u062a \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u0634\u0645\u0627 \u0631\u0627 \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627 \u062f\u0648\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u0645\u0627 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u062f\u0631 \u0644\u06cc\u0648\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0633\u06cc \u062e\u0648\u0627\u0635 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0646\u06cc\u0632 \u062f\u0627\u0631\u062f \u0648 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u067e\u06cc\u0633\u06cc \u062f\u0631 \u0637\u0628 \u0633\u0646\u062a\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0645\u0633 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u0627\u0646\u06cc\u0646 \u062f\u0631 \u067e\u0648\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u062f\u0631 \u0638\u0631\u0641 \u0645\u0633\u06cc \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0644\u0627\u0646\u06cc\u0646 \u062f\u0631 \u0628\u062f\u0646 \u0633\u0641\u06cc\u062f\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0631\u0627 \u06a9\u0645\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%BE%D8%A7%D9%BE%D8%A7%DB%8C%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\"><\/span>\u067e\u0627\u067e\u0627\u06cc\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u067e\u0627\u067e\u0627\u06cc\u0627 \u0645\u06cc\u0648\u0647\u200c\u0627\u06cc \u062e\u0648\u0634\u0645\u0632\u0647 \u0648 \u067e\u0631\u062e\u0627\u0635\u06cc\u062a \u0627\u0633\u062a \u0648 \u062e\u0648\u0631\u062f\u0646 \u0622\u0646 \u0628\u0647\u200c\u0637\u0648\u0631 \u06a9\u0644\u06cc \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a\u06cc \u0646\u06cc\u0632 \u0641\u0627\u06cc\u062f\u0647 \u062f\u0627\u0631\u062f. \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u200c\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u067e\u0648\u0633\u062a\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u067e\u0627\u067e\u0627\u06cc\u0627 \u0627\u0633\u062a.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0646\u0638\u0648\u0631 \u062a\u06a9\u0647\u200c\u0647\u0627\u06cc \u067e\u0627\u067e\u0627\u06cc\u0627 \u0631\u0627 \u0631\u0648\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u0648 \u062a\u0627 \u062e\u0634\u06a9 \u0634\u062f\u0646 \u0622\u0646 \u0635\u0628\u0631 \u06a9\u0646\u06cc\u062f. \u0633\u067e\u0633 \u0622\u0646 \u0631\u0627 \u0628\u0627 \u0622\u0628 \u0648\u0644\u0631\u0645 \u0628\u0634\u0648\u0631\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u067e\u0627\u067e\u0627\u06cc\u0627 \u0628\u0647 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646\u06cc \u0633\u0644\u0648\u0644\u200c\u0647\u0627\u06cc \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a\u0647 \u0645\u0644\u0627\u0646\u06cc\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%DA%AF_%D8%B1%DB%8C%D8%AD%D8%A7%D9%86_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\"><\/span>\u0628\u0631\u06af \u0631\u06cc\u062d\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0631\u06cc\u062d\u0627\u0646 \u062f\u0627\u0631\u0627\u06cc \u062e\u0627\u0635\u06cc\u062a \u0636\u062f\u067e\u06cc\u0631\u06cc\u060c \u0636\u062f\u0628\u0627\u06a9\u062a\u0631\u06cc \u0648 \u0636\u062f\u0648\u06cc\u0631\u0648\u0633 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062f\u0641\u0639 \u0645\u06cc\u06a9\u0631\u0648\u0628\u200c\u0647\u0627 \u0648 \u0631\u0627\u062f\u06cc\u06a9\u0627\u0644\u200c\u0647\u0627\u06cc \u0622\u0632\u0627\u062f \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0646 \u0627\u0632 \u062f\u0631\u0645\u0627\u0646 \u06af\u06cc\u0627\u0647\u06cc \u067e\u06cc\u0633\u06cc \u0635\u0648\u0631\u062a \u06cc\u0627 \u0628\u062f\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0631\u0648\u06cc \u062e\u0648\u0627\u0635 \u0631\u06cc\u062d\u0627\u0646 \u062d\u0633\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u06af\u0631\u0641\u062a\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0646\u062a\u06cc\u062c\u0647 \u0628\u0631\u06af \u0631\u06cc\u062d\u0627\u0646 \u0631\u0627 \u0628\u0627 \u0622\u0628 \u0644\u06cc\u0645\u0648\u06cc \u062a\u0627\u0632\u0647 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0647\u0631 \u0631\u0648\u0632 \u0631\u0648\u06cc \u067e\u0648\u0633\u062a \u062e\u0648\u062f \u0648 \u062f\u0631 \u0645\u062d\u0644 \u0644\u06a9\u200c\u0647\u0627 \u0645\u0627\u0633\u0627\u0698 \u062f\u0647\u06cc\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u06a9\u0627\u0631 \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u0627\u0646\u06cc\u0646 \u0631\u0627 \u0646\u06cc\u0632 \u062a\u062d\u0631\u06cc\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0632 \u0631\u06cc\u062d\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u0631\u06cc\u062d\u0627\u0646 \u0646\u06cc\u0632 \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0646 \u0627\u0632 \u062e\u0627\u0635\u06cc\u062a \u0622\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u0628\u0647 \u062a\u0639\u062f\u06cc\u0644 \u0631\u0646\u06af \u0648 \u0622\u0628\u200c\u0631\u0633\u0627\u0646\u06cc \u0628\u0647 \u067e\u0648\u0633\u062a \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%DA%AF%D8%B1%D8%AF%D9%88_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\"><\/span>\u06af\u0631\u062f\u0648 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0645\u0637\u0644\u0628 \u062f\u0631\u0645\u0627\u0646 \u06af\u06cc\u0627\u0647\u06cc \u067e\u06cc\u0633\u06cc \u0646\u06cc \u0646\u06cc \u0633\u0627\u06cc\u062a \u0622\u0645\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0641\u0648\u0627\u06cc\u062f \u0628\u06cc\u200c\u0634\u0645\u0627\u0631 \u06af\u0631\u062f\u0648 \u06a9\u0645\u06a9 \u0622\u0646 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0627\u06cc \u067e\u06cc\u0633\u06cc \u0627\u0633\u062a. \u062e\u0648\u0631\u062f\u0646 \u062d\u062f\u0627\u0642\u0644 \u06f5 \u0639\u062f\u062f \u06af\u0631\u062f\u0648 \u062f\u0631 \u0631\u0648\u0632 \u0628\u0647 \u0633\u0644\u0627\u0645\u062a \u0628\u062f\u0646 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u0622\u062b\u0627\u0631 \u0648 \u0644\u06a9\u200c\u0647\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0631\u0627 \u0646\u06cc\u0632 \u06a9\u0645\u200c\u0631\u0646\u06af\u200c\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631\u06cc \u0628\u0647\u062a\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u06af\u0631\u062f\u0648 \u0631\u0627 \u062e\u0631\u062f \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0628\u0647\u200c\u0634\u06a9\u0644 \u067e\u0648\u062f\u0631 \u062f\u0631\u0622\u0648\u0631\u062f\u06cc\u062f. \u0633\u067e\u0633 \u067e\u0648\u062f\u0631 \u06af\u0631\u062f\u0648 \u0631\u0627 \u0628\u0627 \u0622\u0628 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062d\u0627\u0644\u062a \u062e\u0645\u06cc\u0631\u06cc \u0628\u0647 \u062e\u0648\u062f \u0628\u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u062e\u0645\u06cc\u0631 \u0631\u0627 \u062d\u062f\u0627\u0642\u0644 \u06f3 \u0628\u0627\u0631 \u062f\u0631 \u0631\u0648\u0632 \u062d\u062f\u0648\u062f \u06f1\u06f5 \u062f\u0642\u06cc\u0642\u0647 \u0631\u0648\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627 \u0645\u0627\u0633\u0627\u0698 \u062f\u0647\u06cc\u062f \u0648 \u0627\u0632 \u062a\u0627\u062b\u06cc\u0631 \u0641\u0648\u0642\u200c\u0627\u0644\u0639\u0627\u062f\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u062f\u0627\u0631\u062f\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<figure id=\"attachment_38712\" aria-describedby=\"caption-attachment-38712\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38712 size-full\" src=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/3.jpeg\" alt=\"\u06af\u0631\u062f\u0648 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/3.jpeg 1200w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/3-300x300.jpeg 300w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/3-1030x1030.jpeg 1030w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/3-80x80.jpeg 80w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/3-768x768.jpeg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-38712\" class=\"wp-caption-text\">\u06af\u0631\u062f\u0648 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%AF_%D8%BA%D8%B0%D8%A7%DB%8C%DB%8C_%DA%A9%D9%87_%D8%AF%D8%B1_%D8%AA%D8%B1%DA%A9%DB%8C%D8%A8%D8%B4%D8%A7%D9%86_%D8%B2%DB%8C%D9%86%DA%A9_%D8%AF%D8%A7%D8%B1%D9%86%D8%AF\"><\/span>\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u062a\u0631\u06a9\u06cc\u0628\u0634\u0627\u0646 \u0632\u06cc\u0646\u06a9 \u062f\u0627\u0631\u0646\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0631\u0639\u0627\u06cc\u062a \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0645\u0646\u0627\u0633\u0628 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0631\u0635 \u06a9\u0645\u06a9 \u0632\u06cc\u0627\u062f\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0632\u06cc\u0646\u06a9 \u06cc\u0627 \u0631\u0648\u06cc \u0627\u0633\u062a.<\/p>\n<p>\u0645\u0642\u062f\u0627\u0631 \u0631\u0648\u06cc \u062f\u0631 \u0628\u062f\u0646 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0645\u0628\u062a\u0644\u0627 \u0628\u0647 \u067e\u06cc\u0633\u06cc \u06a9\u0645\u062a\u0631 \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0633\u0627\u0644\u0645 \u0627\u0633\u062a\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u063a\u0630\u0627\u06cc\u06cc \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0628\u0631\u0635 \u06a9\u0645\u06a9 \u0632\u06cc\u0627\u062f\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u06a9\u0645\u0644 \u0631\u0648\u06cc \u062f\u0631 \u0628\u062f\u0646 \u0631\u0648\u0646\u062f \u0628\u0647\u0628\u0648\u062f \u067e\u0648\u0633\u062a \u0631\u0627 \u062a\u062d\u0631\u06cc\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u06af\u0648\u0634\u062a\u06cc \u062f\u0627\u0631\u0627\u06cc \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0648\u06cc \u0647\u0633\u062a\u0646\u062f. \u0628\u0631\u0627\u06cc \u0631\u0639\u0627\u06cc\u062a \u06cc\u06a9 \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0633\u0627\u0644\u0645 \u0628\u0631\u0627\u06cc \u062d\u0641\u0638 \u0633\u0644\u0627\u0645\u062a \u067e\u0648\u0633\u062a \u062d\u062a\u0645\u0627 \u0627\u0632 \u06cc\u06a9 \u062f\u06a9\u062a\u0631 \u062f\u0631\u0645\u0627\u062a\u0648\u0644\u0648\u0698\u06cc \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%88%DB%8C%D8%AA%D8%A7%D9%85%DB%8C%D9%86_%D8%B3%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\"><\/span>\u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0633\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06a9\u0645\u0628\u0648\u062f \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0633\u06cc \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0645\u0628\u062a\u0644\u0627 \u0628\u0647 \u0628\u0631\u0635 \u0631\u0627\u06cc\u062c \u0627\u0633\u062a. \u0628\u0627 \u0627\u06cc\u0646\u200c\u062d\u0627\u0644 \u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u062f\u0631 \u0645\u0642\u0627\u0644\u0647 \u062f\u0631\u0645\u0627\u0646 \u067e\u06cc\u0633\u06cc \u0646\u06cc \u0646\u06cc \u0633\u0627\u06cc\u062a \u0622\u0645\u062f\u0647 \u0627\u0633\u062a\u060c \u062e\u0648\u0631\u062f\u0646 \u0645\u0631\u06a9\u0628\u0627\u062a\u06cc \u0645\u0627\u0646\u0646\u062f \u067e\u0631\u062a\u0642\u0627\u0644\u060c \u0644\u06cc\u0645\u0648 \u0648 \u06af\u0631\u06cc\u067e \u0641\u0631\u0648\u062a \u0648 \u0645\u06cc\u0648\u0647\u200c\u0647\u0627\u06cc \u062a\u0648\u062a \u0641\u0631\u0646\u06af\u06cc\u060c \u06a9\u06cc\u0648\u06cc\u060c \u0641\u0644\u0641\u0644 \u062f\u0644\u0645\u0647\u200c\u0627\u06cc \u0648 \u0628\u0631\u0648\u06a9\u0644\u06cc \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062f\u0627\u0634\u062a\u0646 \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0633\u06cc \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u0645\u0642\u0627\u062f\u06cc\u0631 \u0632\u06cc\u0627\u062f \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0633\u06cc \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0636\u0631\u0631 \u062f\u0627\u0631\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0641\u0631\u0627\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0633\u06cc \u0632\u06cc\u0627\u062f\u0647\u200c\u0631\u0648\u06cc \u0646\u06a9\u0646\u0646\u062f \u0648 \u0641\u0642\u0637 \u06a9\u0645\u0628\u0648\u062f \u0622\u0646 \u0631\u0627 \u062c\u0628\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D8%B3%D9%84_%D9%88_%D8%A8%D8%B1%DA%AF_%DA%86%D8%B1%DB%8C%D8%B4_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\"><\/span>\u0639\u0633\u0644 \u0648 \u0628\u0631\u06af \u0686\u0631\u06cc\u0634 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u062e\u062a\u0644\u0627\u0644 \u067e\u0648\u0633\u062a\u06cc \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u0628\u062e\u0634\u062f\u060c \u062e\u0648\u0631\u062f\u0646 \u0645\u062e\u0644\u0648\u0637\u06cc \u0627\u0632 \u0622\u0628\u060c \u0639\u0633\u0644 \u0648 \u0686\u0646\u062f \u0628\u0631\u06af \u0644\u0647 \u0634\u062f\u0647 \u0686\u0631\u06cc\u0634 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u0646\u06cc\u0632 \u0628\u0627 \u062a\u0648\u0644\u06cc\u062f \u0631\u0646\u06af\u062f\u0627\u0646\u0647\u200c\u0647\u0627 \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0631\u0627 \u06a9\u0645\u200c\u0631\u0646\u06af\u200c\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B2%D8%B1%D8%AF%DA%86%D9%88%D8%A8%D9%87_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\"><\/span>\u0632\u0631\u062f\u0686\u0648\u0628\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0632\u0631\u062f\u0686\u0648\u0628\u0647 \u0646\u06cc\u0632 \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u062d\u0631\u06cc\u06a9 \u0631\u0646\u06af\u062f\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u06af\u0631\u0641\u062a\u0646 \u0628\u0647\u062a\u0631\u06cc\u0646 \u0646\u062a\u06cc\u062c\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u062f\u0631\u0645\u0627\u0646 \u06af\u06cc\u0627\u0647\u06cc \u067e\u06cc\u0633\u06cc\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0645\u0642\u062f\u0627\u0631\u06cc \u0632\u0631\u062f\u0686\u0648\u0628\u0647 \u0631\u0627 \u0628\u0627 \u0631\u0648\u063a\u0646 \u062e\u0631\u062f\u0644 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0645\u062f\u062a \u06f2\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0631\u0648\u06cc \u0646\u0627\u062d\u06cc\u0647 \u0622\u0633\u06cc\u0628 \u062f\u06cc\u062f\u0647 \u0645\u0627\u0633\u0627\u0698 \u062f\u0647\u06cc\u062f. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u06f2 \u0628\u0627\u0631 \u062f\u0631 \u0631\u0648\u0632 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f.<\/p>\n<p>\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0631\u0648\u063a\u0646 \u0686\u0631\u06cc\u0634 \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0631\u0648\u063a\u0646 \u062e\u0627\u0635\u06cc\u062a \u0636\u062f\u0642\u0627\u0631\u0686 \u0648 \u0636\u062f \u0627\u0644\u062a\u0647\u0627\u0628 \u062f\u0627\u0631\u062f \u0648 \u0628\u0647 \u0622\u0631\u0627\u0645\u0634 \u067e\u0648\u0633\u062a \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0631\u0648\u063a\u0646 \u0686\u0631\u06cc\u0634 \u0628\u0647 \u06cc\u06a9 \u062f\u0633\u062a \u0634\u062f\u0646 \u0631\u0646\u06af \u067e\u0648\u0633\u062a \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u0646\u0638\u0645 \u0627\u0632 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0648 \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u0635\u0648\u0631\u062a \u0645\u0648\u062b\u0631 \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%DA%AF_%D8%AF%D8%B1%D8%AE%D8%AA_%D8%A7%D9%86%D8%A7%D8%B1_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\"><\/span>\u0628\u0631\u06af \u062f\u0631\u062e\u062a \u0627\u0646\u0627\u0631 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u06af\u200c\u0647\u0627\u06cc \u0627\u0646\u0627\u0631 \u062f\u0627\u0631\u0627\u06cc \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u0645\u06a9 \u0632\u06cc\u0627\u062f\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0631\u0627\u06cc \u0645\u0635\u0631\u0641 \u0622\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631\u06af\u200c\u0647\u0627 \u0631\u0627 \u062e\u0634\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u0633\u067e\u0633 \u067e\u0648\u062f\u0631 \u06a9\u0646\u06cc\u062f. \u0631\u0648\u0632\u0627\u0646\u0647 \u062d\u062f\u0648\u062f \u06f8 \u06af\u0631\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u067e\u0648\u062f\u0631 \u0631\u0627 \u0628\u0627 \u0622\u0628 \u0645\u062e\u0644\u0648\u0637 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0646\u0648\u0634\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B2%D9%86%D8%AC%D8%A8%DB%8C%D9%84_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%82%D8%B7%D8%B9%DB%8C_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%A8%D8%B1%D8%B5\"><\/span>\u0632\u0646\u062c\u0628\u06cc\u0644 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0632\u0646\u062c\u0628\u06cc\u0644 \u062f\u0631 \u0637\u0628 \u0633\u0646\u062a\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0646 \u0627\u0632 \u062e\u0627\u0635\u06cc\u062a \u0632\u0646\u062c\u0628\u06cc\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646 \u0631\u0627 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627 \u0631\u0648\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627 \u0645\u0627\u0633\u0627\u0698 \u062f\u0647\u06cc\u062f. \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u0627 \u0632\u0646\u062c\u0628\u06cc\u0644 \u06af\u0631\u0641\u062a\u0646 \u0639\u0635\u0627\u0631\u0647 \u0648 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0645\u062d\u0644\u0648\u0644 \u0631\u0642\u06cc\u0642 \u0634\u062f\u0647 \u0632\u0646\u062c\u0628\u06cc\u0644 \u0628\u0627 \u0622\u0628 \u0627\u0633\u062a. \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u06cc\u0646 \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc \u0631\u0627 \u06f2 \u0628\u0627\u0631 \u062f\u0631 \u0631\u0648\u0632 \u0628\u0646\u0648\u0634\u06cc\u062f. \u0627\u0644\u0628\u062a\u0647 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0637\u0628\u0639 \u06af\u0631\u0645\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u063a\u0630\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f\u060c \u062f\u0631 \u0631\u0639\u0627\u06cc\u062a \u0622\u0646 \u0632\u06cc\u0627\u062f\u0647\u200c\u0631\u0648\u06cc \u0646\u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"_%D8%A2%D9%84%D9%88%D8%A6%D9%87%E2%80%8C%D9%88%D8%B1%D8%A7\"><\/span>\u00a0\u0622\u0644\u0648\u0626\u0647\u200c\u0648\u0631\u0627<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0622\u0644\u0648\u0626\u0647\u200c\u0648\u0631\u0627 \u0645\u0631\u0637\u0648\u0628\u200c\u06a9\u0646\u0646\u062f\u0647\u200c\u0627\u06cc \u0642\u0648\u06cc \u0648 \u0636\u062f\u0627\u0644\u062a\u0647\u0627\u0628 \u0627\u0633\u062a \u0648 \u0628\u0647 \u0639\u0642\u06cc\u062f\u0647 \u0647\u0631 \u062f\u06a9\u062a\u0631 \u067e\u0648\u0633\u062a\u060c \u062e\u0627\u0635\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u067e\u0648\u0633\u062a \u062f\u0627\u0631\u062f. \u0698\u0644 \u0622\u0644\u0648\u0626\u0647\u200c\u0648\u0631\u0627\u06cc \u062a\u0627\u0632\u0647 \u0631\u0627 \u0628\u0647 \u0645\u062f\u062a \u06f2\u06f0 \u062f\u0642\u06cc\u0642\u0647 \u0631\u0648\u06cc \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f \u0628\u0645\u0627\u0644\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0622\u0646 \u0631\u0627 \u0628\u0627 \u0622\u0628 \u0628\u0634\u0648\u06cc\u06cc\u062f. \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u06f2 \u0628\u0627\u0631 \u062f\u0631 \u0647\u0641\u062a\u0647 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B3%D8%B1%DA%A9%D9%87_%D8%B3%DB%8C%D8%A8\"><\/span>\u0633\u0631\u06a9\u0647 \u0633\u06cc\u0628<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0633\u0631\u06a9\u0647 \u0633\u06cc\u0628 \u0628\u0647 \u062a\u06a9\u062b\u06cc\u0631 \u0628\u0627\u06a9\u062a\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0641\u06cc\u062f \u0631\u0648\u062f\u0647 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0628\u0627\u06a9\u062a\u0631\u06cc\u200c\u0647\u0627 \u0641\u0631\u0622\u06cc\u0646\u062f \u0647\u0636\u0645 \u0631\u0627 \u0622\u0633\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0628\u0647 \u0628\u062f\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0645\u0648\u0627\u062f \u0645\u063a\u0630\u06cc \u0631\u0627 \u0628\u0647\u062a\u0631 \u062c\u0630\u0628 \u06a9\u0646\u062f. \u062c\u0630\u0628 \u062f\u0631\u0633\u062a \u0645\u0648\u0627\u062f \u0645\u063a\u0630\u06cc \u0646\u06cc\u0632 \u0628\u0647 \u062f\u0631\u0645\u0627\u0646 \u067e\u06cc\u0633\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648 \u062e\u0648\u0631\u062f\u0646 \u0633\u0631\u06a9\u0647 \u0633\u06cc\u0628 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc \u0627\u0633\u062a.<\/p>\n<p>\u062a\u0646\u0647\u0627 \u06a9\u0627\u0631\u06cc \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0631\u0648\u0632\u0627\u0646\u0647 \u06cc\u06a9 \u0642\u0627\u0634\u0642 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc \u0627\u0632 \u0633\u0631\u06a9\u0647 \u0633\u06cc\u0628 \u0631\u0627 \u0628\u0627 \u06cc\u06a9 \u0644\u06cc\u0648\u0627\u0646 \u0622\u0628 \u0631\u0642\u06cc\u0642 \u06a9\u0646\u06cc\u062f \u0648 \u0622\u0646 \u0631\u0627 \u0646\u06cc\u0645 \u0633\u0627\u0639\u062a \u0642\u0628\u0644 \u0627\u0632 \u063a\u0630\u0627 \u0628\u0646\u0648\u0634\u06cc\u062f.<\/p>\n<figure id=\"attachment_38713\" aria-describedby=\"caption-attachment-38713\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-38713\" src=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/2.jpeg\" alt=\"\u0632\u0646\u062c\u0628\u06cc\u0644 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/2.jpeg 1200w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/2-300x300.jpeg 300w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/2-1030x1030.jpeg 1030w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/2-80x80.jpeg 80w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2022\/10\/2-768x768.jpeg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-38713\" class=\"wp-caption-text\">\u0632\u0646\u062c\u0628\u06cc\u0644 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0642\u0637\u0639\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0631\u0635<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B3%D8%AE%D9%86_%D9%86%D9%87%D8%A7%DB%8C%DB%8C\"><\/span>\u0633\u062e\u0646 \u0646\u0647\u0627\u06cc\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0631\u0648\u06cc \u0638\u0627\u0647\u0631 \u0627\u0641\u0631\u0627\u062f \u062a\u0627\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u062f \u0648 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0639\u0636\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0631\u0627 \u0627\u0630\u06cc\u062a \u06a9\u0646\u062f. \u0628\u0647\u200c\u0647\u0645\u06cc\u0646 \u0639\u0644\u062a \u0645\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0686\u0646\u062f \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0644\u06a9\u0647 \u067e\u06cc\u0633\u06cc \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0631\u062f\u06cc\u0645.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0644\u06a9\u200c\u0647\u0627\u06cc \u067e\u06cc\u0633\u06cc \u0631\u0627 \u06a9\u0627\u0645\u0644\u0627 \u0627\u0632 \u0628\u06cc\u0646 \u0646\u0645\u06cc\u200c\u0628\u0631\u0646\u062f \u0627\u0645\u0627 \u0627\u062b\u0631\u0634 \u0631\u0627 \u06a9\u0645\u0631\u0646\u06af\u200c\u062a\u0631 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0632 \u0628\u06cc\u0634\u062a\u0631 \u0634\u062f\u0646 \u0622\u0646 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06af\u0631 \u0628\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u062f\u0631\u0645\u0627\u0646 \u067e\u06cc\u0633\u06cc \u0628\u0627 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0633\u0627\u0645\u0627\u0646\u0647 \u067e\u0630\u06cc\u0631\u0634\u06f2\u06f4 \u0628\u0627 \u06cc\u06a9 \u062f\u06a9\u062a\u0631 \u067e\u0648\u0633\u062a \u0622\u0646\u0644\u0627\u06cc\u0646 \u0645\u0634\u0648\u0631\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B3%D9%88%D8%A7%D9%84%D8%A7%D8%AA_%D9%85%D8%AA%D8%AF%D8%A7%D9%88%D9%84_%D8%AF%D8%B1_%D9%85%D9%88%D8%B1%D8%AF_%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C\"><\/span>\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644 \u062f\u0631 \u0645\u0648\u0631\u062f \u0631\u0627\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u067e\u06cc\u0633\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0628\u0647 \u06f3 \u0633\u0648\u0627\u0644 \u0645\u062a\u062f\u0627\u0648\u0644 \u067e\u0627\u0633\u062e \u0645\u06cc\u200c\u062f\u0647\u06cc\u0645.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%B1%D8%AF%D9%86_%DA%86%D9%87_%D8%BA%D8%B0%D8%A7%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C_%D8%B6%D8%B1%D8%B1_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span>\u062e\u0648\u0631\u062f\u0646 \u0686\u0647 \u063a\u0630\u0627\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0636\u0631\u0631 \u062f\u0627\u0631\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u0635\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0627\u0632 \u0645\u0635\u0631\u0641 \u0632\u06cc\u0627\u062f \u0627\u0644\u06a9\u0644\u060c \u0628\u0644\u0648\u0628\u0631\u06cc\u060c \u0642\u0647\u0648\u0647\u060c \u0627\u0646\u06af\u0648\u0631\u060c \u0645\u0627\u0647\u06cc\u060c \u06af\u0648\u0634\u062a \u0642\u0631\u0645\u0632\u060c \u06af\u0648\u062c\u0647 \u0641\u0631\u0646\u06af\u06cc \u0648 \u062a\u0631\u0634\u06cc\u062c\u0627\u062a \u067e\u0631\u0647\u06cc\u0632 \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%87_%D8%BA%D8%B0%D8%A7%D9%87%D8%A7%DB%8C%DB%8C_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D9%85%D9%84%D8%A7%D9%86%DB%8C%D9%86_%D8%B1%D8%A7_%D8%A8%DB%8C%D8%B4%D8%AA%D8%B1_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF%D8%9F\"><\/span>\u062c\u0647 \u063a\u0630\u0627\u0647\u0627\u06cc\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u0627\u0646\u06cc\u0646 \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0622 \u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0645\u0647\u0645 \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u0627\u0646\u06cc\u0646 \u0648 \u062f\u0627\u0634\u062a\u0646 \u067e\u0648\u0633\u062a\u06cc \u0633\u0627\u0644\u0645 \u0627\u0633\u062a. \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0622 \u062f\u0631 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a\u060c \u0647\u0648\u06cc\u062c\u060c \u0627\u0633\u0641\u0646\u0627\u062c \u0648 \u0646\u062e\u0648\u062f \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%A8%DB%8C%D9%85%D8%A7%D8%B1%DB%8C_%D9%BE%DB%8C%D8%B3%DB%8C_%D8%AF%D8%B1_%D8%B7%D8%A8_%D8%B3%D9%86%D8%AA%DB%8C_%D9%82%D8%A7%D8%A8%D9%84_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span>\u0622\u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u062f\u0631 \u0637\u0628 \u0633\u0646\u062a\u06cc \u0642\u0627\u0628\u0644 \u062f\u0631\u0645\u0627\u0646 \u0627\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0645\u0648\u0627\u0642\u0639 \u067e\u06cc\u0633\u06cc \u06cc\u0627 \u0628\u0631\u0635 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0627\u062f\u0627\u0645\u200c\u0627\u0644\u0639\u0645\u0631 \u0627\u0633\u062a \u0648 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647\u200c\u0634\u06a9\u0644 \u06a9\u0627\u0645\u0644 \u0622\u0646 \u0631\u0627 \u062f\u0631\u0645\u0627\u0646 \u06a9\u0631\u062f. \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc \u0633\u0627\u0644\u0645 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u0648 \u0645\u0631\u0627\u062c\u0639\u0647 \u0628\u0647 \u062f\u06a9\u062a\u0631 \u062f\u0631\u0645\u0627\u062a\u0648\u0644\u0648\u0698\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0628\u062f\u062a\u0631 \u0634\u062f\u0646 \u0622\u0646 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u06cc\u0633\u06cc \u06cc\u0627 \u0628\u0631\u0635 (\u0628\u0647 \u0627\u0646\u06af\u0644\u06cc\u0633\u06cc: Vitiligo) \u0646\u0648\u0639\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631 \u0627\u062b\u0631 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0622\u0646 \u062f\u0631 \u0638\u0627\u0647\u0631 \u067e\u0648\u0633\u062a \u0628\u06cc\u0645\u0627\u0631 \u0644\u06a9\u0647\u200c\u0647\u0627\u06cc \u0633\u0641\u06cc\u062f\u06cc \u0646\u0645\u0627\u06cc\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u0645\u0627 \u062f\u0644\u06cc\u0644 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u0686\u06af\u0648\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0627 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0627\u062b\u0631 \u0622\u0646 \u0631\u0627 \u06a9\u0645\u200c\u0631\u0646\u06af\u200c\u062a\u0631 \u06a9\u0631\u062f\u061f \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0637\u0644\u0628 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627 \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u067e\u0627\u0633\u062e \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644\u200c\u0647\u0627\u060c &hellip;<\/p>\n","protected":false},"author":27,"featured_media":38711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[705],"tags":[3630],"class_list":["post-38710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dermatology","tag-3630"],"_links":{"self":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/posts\/38710"}],"collection":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/comments?post=38710"}],"version-history":[{"count":0,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/posts\/38710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/media\/38711"}],"wp:attachment":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/media?parent=38710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/categories?post=38710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/tags?post=38710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}