{"id":6853,"date":"2020-09-13T17:47:43","date_gmt":"2020-09-13T13:17:43","guid":{"rendered":"https:\/\/www.paziresh24.com\/blog\/6853\/%d8%af%d8%a7%d8%b1%d9%88%db%8c-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af-%da%a9%d8%a7%d8%b1%d8%a8%d8%b1%d8%af-%d8%8c-%d9%85%d9%82%d8%af%d8%a7%d8%b1-%d9%88-%d8%b1%d9%88%d8%b4-%d9%85%d8%b5%d8%b1%d9%81\/"},"modified":"2022-04-10T11:35:05","modified_gmt":"2022-04-10T07:05:05","slug":"drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af","status":"publish","type":"post","link":"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/","title":{"rendered":"\u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u0628\u0631\u0627\u06cc \u0628\u06cc \u062e\u0648\u0627\u0628\u06cc \u0648 \u0628\u06cc \u0642\u0631\u0627\u0631\u06cc \u06a9\u0648\u062f\u06a9"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter-rtl ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D9%86%D8%A7%D9%85_%D8%AA%D8%AC%D8%A7%D8%B1%DB%8C_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D8%A7%D8%B4%DA%A9%D8%A7%D9%84_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0627\u0634\u06a9\u0627\u0644 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u06cc \u0628\u06cc \u0633\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u06cc \u0628\u06cc \u0633\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D9%85%D9%82%D8%AF%D8%A7%D8%B1_%D9%88_%D8%B1%D9%88%D8%B4_%D9%85%D8%B5%D8%B1%D9%81_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0645\u0642\u062f\u0627\u0631 \u0648 \u0631\u0648\u0634 \u0645\u0635\u0631\u0641 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u00a0\u00a0\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D9%85%D9%88%D8%A7%D8%B1%D8%AF_%D9%85%D9%86%D8%B9_%D9%85%D8%B5%D8%B1%D9%81_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0645\u0648\u0627\u0631\u062f \u0645\u0646\u0639 \u0645\u0635\u0631\u0641 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D8%AA%D8%AF%D8%A7%D8%AE%D9%84%D8%A7%D8%AA_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u062a\u062f\u0627\u062e\u0644\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D8%B9%D9%88%D8%A7%D8%B1%D8%B6_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0639\u0648\u0627\u0631\u0636 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D9%85%D8%B5%D8%B1%D9%81_%D8%A8%DB%8C%D8%B4_%D8%A7%D8%B2_%D8%AD%D8%AF_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF_%D9%85%D8%B3%D9%85%D9%88%D9%85%DB%8C%D8%AA_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%A8%D8%A7_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0645\u0635\u0631\u0641 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f (\u0645\u0633\u0645\u0648\u0645\u06cc\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0627 \u0628\u06cc \u0628\u06cc \u0633\u062f)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.paziresh24.com\/blog\/6853\/drug-%d8%af%d8%a7%d8%b1%d9%88-%d8%a8%db%8c-%d8%a8%db%8c-%d8%b3%d8%af\/#%D8%B4%D8%B1%D8%A7%DB%8C%D8%B7_%D9%86%DA%AF%D9%87%D8%AF%D8%A7%D8%B1%DB%8C_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\" >\u0634\u0631\u0627\u06cc\u0637 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u00a0\u00a0\u00a0<\/a><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%A7%D9%85_%D8%AA%D8%AC%D8%A7%D8%B1%DB%8C_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Goldaru<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.paziresh24.com\/blog\/33857\/%d8%a7%db%8c%d9%86%d8%b3%d9%88%d9%85%d9%86%db%8c%d8%a7-%db%8c%d8%a7-%d8%a8%db%8c%d8%ae%d9%88%d8%a7%d8%a8%db%8c\/\" data-internallinksmanager029f6b8e52c=\"1939\" title=\"\u0627\u062e\u062a\u0644\u0627\u0644 \u0627\u06cc\u0646\u0633\u0648\u0645\u0646\u06cc\u0627 \u06cc\u0627 \u0628\u06cc\u200c\u062e\u0648\u0627\u0628\u06cc \u0686\u06cc\u0633\u062a\u061f \u0622\u06cc\u0627 \u062f\u0631\u0645\u0627\u0646 \u062f\u0627\u0631\u062f\u061f\">\u0628\u06cc\u200c\u062e\u0648\u0627\u0628\u06cc<\/a> \u0648 \u0628\u06cc \u0642\u0631\u0627\u0631\u06cc \u06a9\u0648\u062f\u06a9<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B4%DA%A9%D8%A7%D9%84_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0627\u0634\u06a9\u0627\u0644 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u06cc \u0628\u06cc \u0633\u062f <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0634\u0631\u0628\u062a<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B7%D9%84%D8%A7%D8%B9%D8%A7%D8%AA_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u06cc \u0628\u06cc \u0633\u062f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u06cc\u06a9 \u062f\u0627\u0631\u0648\u06cc \u06af\u06cc\u0627\u0647\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u200c\u062e\u0648\u0627\u0628\u06cc \u0648 \u0646\u0627\u0622\u0631\u0627\u0645\u06cc \u06a9\u0648\u062f\u06a9 \u062a\u062c\u0648\u06cc\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648 \u0627\u0632 \u06af\u06cc\u0627\u0647\u0627\u0646 \u06af\u0644 \u0633\u0627\u0639\u062a\u06cc\u060c \u0632\u0646\u062c\u0628\u06cc\u0644\u060c \u0628\u0627\u0628\u0648\u0646\u0647\u060c \u0628\u0627\u062f\u0631\u0646\u062c\u0628\u0648\u0628\u0647\u060c \u0646\u0639\u0646\u0627\u0639 \u0641\u0644\u0641\u0644\u06cc\u060c \u0639\u0646\u0627\u0628 \u062a\u0634\u06a9\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u062b\u0631\u0627\u062a \u0647\u0645 \u0627\u0641\u0632\u0627\u0626\u06cc \u0627\u06cc\u0646 6 \u06af\u06cc\u0627\u0647 \u0633\u0628\u0628 \u0631\u0641\u0639 \u0627\u0636\u0637\u0631\u0627\u0628 \u0648 \u0628\u06cc\u200c\u062e\u0648\u0627\u0628\u06cc\u060c \u06a9\u0627\u0647\u0634 \u0646\u0641\u062e \u0648 \u0627\u0633\u067e\u0627\u0633\u0645 \u062f\u0633\u062a\u06af\u0627\u0647 \u06af\u0648\u0627\u0631\u0634 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0647 \u0627\u06cc\u0646 \u0637\u0631\u06cc\u0642 \u0628\u06cc\u200c\u0642\u0631\u0627\u0631\u06cc \u06a9\u0648\u062f\u06a9 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u0628\u062e\u0634\u062f \u0648 \u062e\u0648\u0627\u0628 \u0622\u0631\u0627\u0645\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u06cc\u0627 \u0646\u0648\u0632\u0627\u062f \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p><a href=\"https:\/\/www.paziresh24.com\/\" data-internallinksmanager029f6b8e52c=\"13\" title=\"\u067e\u0630\u06cc\u0631\u0634 \u06f2\u06f4\">\u067e\u0630\u06cc\u0631\u0634 24<\/a>\u060c \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0635\u0648\u0631\u062a 24 \u0633\u0627\u0639\u062a\u0647 \u0648 \u0622\u0646\u0644\u0627\u06cc\u0646 \u0628\u0627 <a href=\"https:\/\/www.paziresh24.com\/consult\/pediatrics?refafname=blog-medicinebank-Babysed-text1-pediatrics\"><strong>\u067e\u0632\u0634\u06a9 \u0622\u0646\u0644\u0627\u06cc\u0646 \u0627\u0637\u0641\u0627\u0644\u060c \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u0632\u0627\u062f\u0627\u0646<\/strong><\/a> \u0645\u0634\u0648\u0631\u062a \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u0645\u0631\u0627\u062c\u0639\u0647 \u062d\u0636\u0648\u0631\u06cc \u0628\u0647 \u067e\u0632\u0634\u06a9\u060c \u0627\u0632 <a href=\"https:\/\/www.paziresh24.com\/consult\/pediatrics?refafname=blog-medicinebank-Babysed-text1-pediatrics\"><strong>\u0645\u062a\u062e\u0635\u0635 \u0627\u0637\u0641\u0627\u0644\u060c \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u0632\u0627\u062f\u0627\u0646<\/strong> <\/a>\u0648 \u06cc\u0627 <span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u062f\u06a9\u062a\u0631 \u0628\u06cc \u062e\u0648\u0627\u0628\u06cc&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:1325889,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:1,&quot;11&quot;:3,&quot;12&quot;:1,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:1136076},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11,&quot;21&quot;:1,&quot;23&quot;:1}\" data-sheets-hyperlink=\"https:\/\/www.paziresh24.com\/s\/ir\/q-%D8%AF%DA%A9%D8%AA%D8%B1-%D8%A8%DB%8C-%D8%AE%D9%88%D8%A7%D8%A8%DB%8C\/\"><a class=\"in-cell-link\" href=\"https:\/\/www.paziresh24.com\/s\/ir\/q-%D8%AF%DA%A9%D8%AA%D8%B1-%D8%A8%DB%8C-%D8%AE%D9%88%D8%A7%D8%A8%DB%8C\/\" target=\"_blank\" rel=\"noopener\">\u062f\u06a9\u062a\u0631 \u0628\u06cc \u062e\u0648\u0627\u0628\u06cc<\/a> <\/span>\u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u0627\u06cc\u0631\u0627\u0646\u060c \u0646\u0648\u0628\u062a \u0648\u06cc\u0632\u06cc\u062a \u062d\u0636\u0648\u0631\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23504 aligncenter\" src=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f1.jpg\" alt=\"\u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f\" width=\"400\" height=\"400\" srcset=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f1.jpg 400w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f1-300x300.jpg 300w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f1-80x80.jpg 80w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%AF%D8%A7%D8%B1_%D9%88_%D8%B1%D9%88%D8%B4_%D9%85%D8%B5%D8%B1%D9%81_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0645\u0642\u062f\u0627\u0631 \u0648 \u0631\u0648\u0634 \u0645\u0635\u0631\u0641 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u00a0\u00a0\u00a0\u00a0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul style=\"text-align: justify;\">\n<li>\u0642\u0628\u0644 \u0627\u0632 \u0634\u0631\u0648\u0639 \u062f\u0631\u0645\u0627\u0646 \u0628\u0627 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f (Babysed Syrup) \u0628\u0631\u0648\u0634\u0648\u0631 \u062f\u0627\u0631\u0648\u06cc\u06cc \u062f\u0627\u062e\u0644 \u0628\u0633\u062a\u0647 \u0631\u0627 \u0628\u0647 \u062f\u0642\u062a \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u0628\u0631\u0648\u0634\u0648\u0631 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062c\u0627\u0645\u0639\u06cc \u0631\u0627 \u0631\u0627\u062c\u0639 \u0628\u0647 \u062f\u0627\u0631\u0648 \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f\u0647 \u0648 \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u062c\u0627\u0646\u0628\u06cc \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u0622\u0646 \u0645\u0637\u0644\u0639 \u0634\u0648\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06af\u0631 \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0645\u0635\u0631\u0641 \u0622\u0646 \u0628\u0627 \u0633\u0624\u0627\u0644\u0627\u062a\u06cc \u0631\u0648\u0628\u0631\u0648 \u0647\u0633\u062a\u06cc\u062f \u0628\u0627 \u067e\u0632\u0634\u06a9 \u062e\u0648\u062f \u0645\u0634\u0648\u0631\u062a \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/li>\n<li>\u062f\u0648\u0632 \u0648 \u0645\u0642\u062f\u0627\u0631 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u0627\u0632 \u0641\u0631\u062f\u06cc \u0628\u0647 \u0641\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a. \u0644\u0630\u0627 \u062f\u0627\u0631\u0648 \u0631\u0627 \u062f\u0642\u06cc\u0642\u0627\u064b \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u067e\u0632\u0634\u06a9 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u06cc\u0627 \u0646\u0648\u0632\u0627\u062f \u062a\u062c\u0648\u06cc\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0648\u062f\u0647 \u0648 \u0627\u0632 \u06a9\u0645 \u06cc\u0627 \u0632\u06cc\u0627\u062f \u06a9\u0631\u062f\u0646 \u062e\u0648\u062f\u0633\u0631\u0627\u0646\u0647 \u0645\u0642\u062f\u0627\u0631 \u0648 \u0645\u062f\u062a \u0632\u0645\u0627\u0646 \u0645\u0635\u0631\u0641 \u0627\u062c\u062a\u0646\u0627\u0628 \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/li>\n<li>\u062f\u0648\u0632 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u0631\u0627 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u067e\u06cc\u0645\u0627\u0646\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u0648 (5\/2 \u0633\u06cc \u0633\u06cc \u0648 5 \u0633\u06cc \u0633\u06cc) \u0645\u0637\u0627\u0628\u0642 \u062f\u0633\u062a\u0648\u0631 \u067e\u0632\u0634\u06a9 \u0628\u0631\u0627\u06cc \u06a9\u0648\u062f\u06a9 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f:<\/li>\n<li>\u0627\u0632 \u0628\u062f\u0648 \u062a\u0648\u0644\u062f \u062a\u0627 \u06cc\u06a9 \u0645\u0627\u0647\u06af\u06cc: \u0646\u0635\u0641 \u0642\u0627\u0634\u0642 \u0645\u0631\u0628\u0627\u062e\u0648\u0631\u06cc (5\/2 \u0633\u06cc \u0633\u06cc)<\/li>\n<li>\u0627\u0632 \u06cc\u06a9 \u0645\u0627\u0647\u06af\u06cc \u062a\u0627 \u0634\u0634 \u0645\u0627\u0647\u06af\u06cc: \u06cc\u06a9 \u0642\u0627\u0634\u0642 \u0645\u0631\u0628\u0627\u062e\u0648\u0631\u06cc (5 \u0633\u06cc \u0633\u06cc)<\/li>\n<li>\u0634\u0634 \u0645\u0627\u0647\u06af\u06cc \u0628\u0647 \u0628\u0627\u0644\u0627: \u062f\u0648 \u0642\u0627\u0634\u0642 \u0645\u0631\u0628\u0627\u062e\u0648\u0631\u06cc (10 \u0633\u06cc \u0633\u06cc)<\/li>\n<li>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u0645\u0635\u0631\u0641 \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648\u060c \u0645\u0634\u06a9\u0644 \u0646\u0627\u0622\u0631\u0627\u0645\u06cc \u0646\u0648\u0632\u0627\u062f \u06cc\u0627 \u06a9\u0648\u062f\u06a9 \u0628\u0631\u0637\u0631\u0641 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648 \u0631\u0627 \u0642\u0637\u0639 \u0648 \u0628\u0627 \u067e\u0632\u0634\u06a9 \u0641\u0631\u0632\u0646\u062f\u062a\u0627\u0646 \u0645\u0634\u0648\u0631\u062a \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/li>\n<li>\u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f\u060c \u062f\u0631 24 \u0633\u0627\u0639\u062a\u060c \u0628\u06cc\u0634 \u0627\u0632 6 \u0645\u0631\u062a\u0628\u0647 \u0645\u0635\u0631\u0641 <strong>\u0646\u0634\u0648\u062f<\/strong>.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D8%A7%D8%B1%D8%AF_%D9%85%D9%86%D8%B9_%D9%85%D8%B5%D8%B1%D9%81_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0645\u0648\u0627\u0631\u062f \u0645\u0646\u0639 \u0645\u0635\u0631\u0641 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul style=\"text-align: justify;\">\n<li>\u0628\u0647 \u062a\u0627\u0631\u06cc\u062e \u0627\u0646\u0642\u0636\u0627\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f (Babysed Syrup) \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0627\u06af\u0631 \u062f\u0627\u0631\u0648\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0633\u062a\u062a\u0627\u0646 \u0627\u0633\u062a \u062a\u0627\u0631\u06cc\u062e \u0627\u0646\u0642\u0636\u0627\u06cc \u0622\u0646 \u062a\u0645\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u0632 \u0645\u0635\u0631\u0641 \u0622\u0646 \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u0647\u0631\u06af\u0632 \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648 \u0631\u0627 \u0628\u0647 \u0641\u0631\u062f \u062f\u06cc\u06af\u0631\u06cc \u062d\u062a\u06cc \u0628\u0627 \u0639\u0644\u0627\u0626\u0645 \u0645\u0634\u0627\u0628\u0647 \u062e\u0648\u062f\u062a\u0627\u0646 \u062a\u062c\u0648\u06cc\u0632 \u0646\u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u0686\u0646\u0627\u0646\u0686\u0647 \u0641\u0631\u0632\u0646\u062f\u062a\u0627\u0646 \u0634\u0631\u0627\u06cc\u0637 \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062e\u0627\u0635\u06cc \u062f\u0627\u0631\u062f\u060c \u0642\u0628\u0644 \u0627\u0632 \u062a\u062c\u0648\u06cc\u0632 \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648\u060c \u067e\u0632\u0634\u06a9 \u0631\u0627 \u0645\u0637\u0644\u0639 \u0633\u0627\u0632\u06cc\u062f. \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0627\u06af\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0632\u06cc\u0631 \u0631\u0627 \u062f\u0627\u0631\u062f:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u062d\u0633\u0627\u0633\u06cc\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648 \u06cc\u0627 \u062f\u06cc\u06af\u0631 \u062f\u0627\u0631\u0648\u0647\u0627 \u0648 \u0645\u0648\u0627\u062f<\/li>\n<li>\u0645\u0634\u06a9\u0644\u0627\u062a \u06a9\u0644\u06cc\u0648\u06cc<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%AF%D8%A7%D8%AE%D9%84%D8%A7%D8%AA_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u062a\u062f\u0627\u062e\u0644\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u062a\u062f\u0627\u062e\u0644\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0639\u0645\u0644\u06a9\u0631\u062f \u0648 \u062a\u0623\u062b\u06cc\u0631 \u062f\u0627\u0631\u0648\u0647\u0627 \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u062f \u06cc\u0627 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0631\u06cc\u0633\u06a9 \u0628\u0631\u0648\u0632 \u0639\u0648\u0627\u0631\u0636 \u062c\u0627\u0646\u0628\u06cc \u0622\u0646\u0647\u0627 \u0634\u0648\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0645\u0635\u0631\u0641 \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648\u060c \u0644\u06cc\u0633\u062a \u062a\u0645\u0627\u0645 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0641\u0631\u0632\u0646\u062f\u062a\u0627\u0646 \u0645\u0635\u0631\u0641 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0627\u0639\u0645 \u0627\u0632 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062a\u062c\u0648\u06cc\u0632\u06cc \u0648 \u063a\u06cc\u0631\u062a\u062c\u0648\u06cc\u0632\u06cc (\u06af\u06cc\u0627\u0647\u06cc\u060c \u0645\u06a9\u0645\u0644 \u0648 &#8230;) \u0631\u0627 \u0628\u0627 \u067e\u0632\u0634\u06a9 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f.<\/p>\n<p><a href=\"https:\/\/www.paziresh24.com\/consult\/pharmacology?refafname=blog-medicinebank-Babysed-text2-pharmacology\"><strong>\u062f\u0627\u0631\u0648\u0633\u0627\u0632 \u0622\u0646\u0644\u0627\u06cc\u0646<\/strong><\/a> \u0646\u06cc\u0632 \u0628\u0647 \u0635\u0648\u0631\u062a 24 \u0633\u0627\u0639\u062a\u0647 \u0648 \u0622\u0646\u0644\u0627\u06cc\u0646 \u0622\u0645\u0627\u062f\u0647 \u067e\u0627\u0633\u062e\u06af\u0648\u06cc\u06cc \u0628\u0647 \u0633\u0624\u0627\u0644\u0627\u062a \u0634\u0645\u0627\u0633\u062a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23505 aligncenter\" src=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f2.jpg\" alt=\"\u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f\" width=\"450\" height=\"338\" srcset=\"https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f2.jpg 450w, https:\/\/www.paziresh24.com\/blog\/wp-content\/uploads\/2020\/09\/\u0634\u0631\u0628\u062a-\u0628\u06cc-\u0628\u06cc-\u0633\u062f2-300x225.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B9%D9%88%D8%A7%D8%B1%D8%B6_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0639\u0648\u0627\u0631\u0636 \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0647\u0645\u0647 \u062f\u0627\u0631\u0648\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0639\u0648\u0627\u0631\u0636 \u062c\u0627\u0646\u0628\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u0646\u062f. \u0627\u0645\u0627 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0646\u06cc\u0632 \u0647\u06cc\u0686 \u0646\u0648\u0639 \u0639\u0627\u0631\u0636\u0647\u200c\u0627\u06cc \u0628\u0631\u0648\u0632 \u0646\u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u06cc\u06a9\u0633\u0631\u06cc \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u0646\u06cc\u0632 \u0628\u0639\u062f \u0627\u0632 \u06af\u0630\u0634\u062a \u0645\u062f\u062a \u06a9\u0648\u062a\u0627\u0647\u06cc \u0627\u0632 \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648\u060c \u0627\u0632 \u0628\u06cc\u0646 \u0645\u06cc\u200c\u0631\u0648\u0646\u062f.<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u062a\u0627 \u0628\u0647 \u062d\u0627\u0644 \u06af\u0632\u0627\u0631\u0634\u06cc \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u062c\u0627\u0646\u0628\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u06af\u0632\u0627\u0631\u0634 \u0646\u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u0645\u0627 \u0686\u0646\u0627\u0646\u0686\u0647 \u06a9\u0648\u062f\u06a9\u062a\u0627\u0646 \u0639\u0644\u0627\u0626\u0645\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0645\u0635\u0631\u0641 \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648 \u0627\u0633\u062a \u0628\u0627 \u067e\u0632\u0634\u06a9 \u0627\u0648 \u0645\u0634\u0648\u0631\u062a \u0646\u0645\u0627\u06cc\u06cc\u062f.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B5%D8%B1%D9%81_%D8%A8%DB%8C%D8%B4_%D8%A7%D8%B2_%D8%AD%D8%AF_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF_%D9%85%D8%B3%D9%85%D9%88%D9%85%DB%8C%D8%AA_%D8%AF%D8%A7%D8%B1%D9%88%DB%8C%DB%8C_%D8%A8%D8%A7_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0645\u0635\u0631\u0641 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f (\u0645\u0633\u0645\u0648\u0645\u06cc\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0627 \u0628\u06cc \u0628\u06cc \u0633\u062f) <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul style=\"text-align: justify;\">\n<li>\u0627\u06cc\u0646 \u062f\u0627\u0631\u0648 \u0631\u0627 \u0628\u06cc\u0634 \u0627\u0632 \u062f\u0648\u0632 \u062a\u062c\u0648\u06cc\u0632 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u067e\u0632\u0634\u06a9\u060c \u0628\u0647 \u0646\u0648\u0632\u0627\u062f \u06cc\u0627 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0646\u062f\u0647\u06cc\u062f.<\/li>\n<li>\u0627\u06af\u0631 \u0627\u062d\u0633\u0627\u0633 \u06a9\u0631\u062f\u06cc\u062f \u06a9\u0647 \u0641\u0631\u0632\u0646\u062f\u062a\u0627\u0646 \u062f\u0686\u0627\u0631 \u0645\u0633\u0645\u0648\u0645\u06cc\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0639\u0644\u0627\u0626\u0645\u06cc \u0645\u0627\u0646\u0646\u062f \u062e\u0648\u0627\u0628 \u0622\u0644\u0648\u062f\u06af\u06cc \u0634\u062f\u06cc\u062f\u060c <a href=\"https:\/\/www.paziresh24.com\/blog\/17342\/%d8%aa%d9%86%da%af%db%8c-%d9%86%d9%81%d8%b3\/\" data-internallinksmanager029f6b8e52c=\"2464\" title=\"\u0639\u0644\u062a \u062a\u0646\u06af\u06cc \u0646\u0641\u0633 \u0648 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062a\u0646\u06af\u06cc \u0646\u0641\u0633\">\u062a\u0646\u06af\u06cc \u0646\u0641\u0633<\/a>\u060c <a href=\"https:\/\/www.paziresh24.com\/blog\/9132\/why-do-we-faint\/\" data-internallinksmanager029f6b8e52c=\"1684\" title=\"\u0686\u0631\u0627 \u063a\u0634 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u061f\">\u063a\u0634<\/a> \u0648 \u0636\u0639\u0641 (\u0627\u0632 \u062d\u0627\u0644 \u0631\u0641\u062a\u0646) \u062f\u0631 \u0627\u0648 \u062f\u06cc\u062f\u06cc\u062f\u060c \u0641\u0648\u0631\u0627\u064b \u0628\u0627 \u0627\u0648\u0631\u0698\u0627\u0646\u0633 \u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B4%D8%B1%D8%A7%DB%8C%D8%B7_%D9%86%DA%AF%D9%87%D8%AF%D8%A7%D8%B1%DB%8C_%D8%B4%D8%B1%D8%A8%D8%AA_%D8%A8%DB%8C_%D8%A8%DB%8C_%D8%B3%D8%AF\"><\/span><strong>\u0634\u0631\u0627\u06cc\u0637 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u00a0\u00a0\u00a0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li style=\"text-align: justify;\">\u062f\u0627\u0631\u0648 \u0631\u0627 \u062f\u0648\u0631 \u0627\u0632 \u062f\u0633\u062a\u0631\u0633 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0646\u06af\u0647 \u062f\u0627\u0631\u06cc\u062f.<\/li>\n<li style=\"text-align: justify;\">\u062f\u0627\u0631\u0648 \u0631\u0627 \u062f\u0631 \u062c\u0627\u06cc\u06cc \u062e\u0634\u06a9 \u0648 \u062e\u0646\u06a9 \u0648 \u0628\u0647 \u062f\u0648\u0631 \u0627\u0632 \u06af\u0631\u0645\u0627 \u0648 \u062a\u0627\u0628\u0634 \u0646\u0648\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0646\u06af\u0647 \u062f\u0627\u0631\u06cc\u062f.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n\t\t<div class=\"box warning  \">\n\t\t\t<div class=\"box-inner-block\">\n\t\t\t\t<span class=\"fa tie-shortcode-boxicon\"><\/span>\u0645\u0637\u0627\u0644\u0628\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0642\u0627\u0644\u0647 \u0628\u0627\u0644\u0627 \u0630\u06a9\u0631 \u0634\u062f\u060c \u0641\u0642\u0637 \u0648 \u0641\u0642\u0637 \u062c\u0646\u0628\u0647 \u0622\u06af\u0627\u0647\u06cc \u0628\u062e\u0634\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0634\u0645\u0627 \u062f\u0648\u0633\u062a\u0627\u0646 \u0639\u0632\u06cc\u0632 \u0631\u0627 \u062f\u0627\u0631\u062f\u060c \u0648 \u0628\u0647 \u0647\u06cc\u0686 \u0648\u062c\u0647 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u062a\u0648\u0635\u06cc\u0647 \u067e\u0632\u0634\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0646\u06cc\u0633\u062a. \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u0631\u0627\u06cc \u0645\u0635\u0631\u0641 \u06a9\u0631\u062f\u0646 \u062f\u0627\u0631\u0648 \u0648 \u062f\u0627\u0646\u0633\u062a\u0646 \u0639\u0648\u0627\u0631\u0636 \u062c\u0627\u0646\u0628\u06cc \u0622\u0646 \u0628\u0627\u062a\u0648\u062c\u0647 \u0628\u0647 \u0633\u0648\u0627\u0628\u0642 \u067e\u0632\u0634\u06a9\u06cc \u062e\u0648\u062f \u0628\u0627 \u062f\u06a9\u062a\u0631 \u0645\u062a\u062e\u0635\u0635 \u0645\u0634\u0648\u0631\u062a \u06a9\u0646\u06cc\u062f. \n\t\t\t<\/div>\n\t\t<\/div>\n\t\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.paziresh24.com\/consult\/pediatrics?refafname=blog-medicinebank-Babysed-button1-pediatrics\" class=\"shortc-button medium green\">\u0634\u0631\u0648\u0639 \u06af\u0641\u062a\u06af\u0648\u06cc \u0622\u0646\u0644\u0627\u06cc\u0646 \u0628\u0627 \u0645\u062a\u062e\u0635\u0635 \u06a9\u0648\u062f\u06a9\u0627\u0646 \u0648 \u0646\u0648\u0632\u0627\u062f\u0627\u0646<\/a>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0627\u0645 \u062a\u062c\u0627\u0631\u06cc \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f Goldaru \u06a9\u0627\u0631\u0628\u0631\u062f \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u0628\u06cc\u200c\u062e\u0648\u0627\u0628\u06cc \u0648 \u0628\u06cc \u0642\u0631\u0627\u0631\u06cc \u06a9\u0648\u062f\u06a9 \u0627\u0634\u06a9\u0627\u0644 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u06cc \u0628\u06cc \u0633\u062f \u0634\u0631\u0628\u062a \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u06cc \u0628\u06cc \u0633\u062f \u0634\u0631\u0628\u062a \u0628\u06cc \u0628\u06cc \u0633\u062f \u06cc\u06a9 \u062f\u0627\u0631\u0648\u06cc \u06af\u06cc\u0627\u0647\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u200c\u062e\u0648\u0627\u0628\u06cc \u0648 \u0646\u0627\u0622\u0631\u0627\u0645\u06cc \u06a9\u0648\u062f\u06a9 \u062a\u062c\u0648\u06cc\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u062f\u0627\u0631\u0648 \u0627\u0632 \u06af\u06cc\u0627\u0647\u0627\u0646 \u06af\u0644 \u0633\u0627\u0639\u062a\u06cc\u060c \u0632\u0646\u062c\u0628\u06cc\u0644\u060c \u0628\u0627\u0628\u0648\u0646\u0647\u060c \u0628\u0627\u062f\u0631\u0646\u062c\u0628\u0648\u0628\u0647\u060c \u0646\u0639\u0646\u0627\u0639 &hellip;<\/p>\n","protected":false},"author":27,"featured_media":13823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[765],"tags":[],"class_list":["post-6853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drugs"],"_links":{"self":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/posts\/6853"}],"collection":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/comments?post=6853"}],"version-history":[{"count":0,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/posts\/6853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/media\/13823"}],"wp:attachment":[{"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/media?parent=6853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/categories?post=6853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paziresh24.com\/blog\/wp-json\/wp\/v2\/tags?post=6853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}